{"id":28364,"date":"2015-01-18T19:57:16","date_gmt":"2015-01-18T18:57:16","guid":{"rendered":"http:\/\/aliens-project.de\/blog\/?p=28364"},"modified":"2015-01-18T23:05:57","modified_gmt":"2015-01-18T22:05:57","slug":"thau-the-timekeeper","status":"publish","type":"post","link":"https:\/\/aliens-project.de\/blog\/2015\/01\/18\/thau-the-timekeeper\/","title":{"rendered":"THAU -The Timekeeper"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"\/\/www.youtube.com\/embed\/Jwt-FrtQvxk\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Thau Recording-Session #8 im Dezember 2014<\/p>\n<p>Ein ganz besonderer Dank geht hiermit an Herrn Bernhard Schmidt, der uns in seinem privaten <a href=\"http:\/\/www.turmuhrenmuseum-gelnhausen.de\/\" target=\"_blank\">Turmuhrenmuseum<\/a> in Gelnhausen Fotografieren und Filmen lie\u00df und uns sehr viel \u00fcber die Geschichte und die Technik dieser wundersch\u00f6nen Exponate erz\u00e4hlen konnte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thau Recording-Session #8 im Dezember 2014 Ein ganz besonderer Dank geht hiermit an Herrn Bernhard Schmidt, der uns in seinem privaten Turmuhrenmuseum in Gelnhausen Fotografieren und Filmen lie\u00df und uns sehr viel \u00fcber die Geschichte und die Technik dieser wundersch\u00f6nen Exponate erz\u00e4hlen konnte.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,1341,4,1342,1533],"tags":[21,862,1424,1537,1386,1496,1294,1684,1560],"class_list":["post-28364","post","type-post","status-publish","format-standard","hentry","category-aliens-project","category-bernd-michael-land-2","category-synthesizer","category-synxss-studio-2","category-thau","tag-ambient","tag-bernd-michael-land","tag-chill-out","tag-electronic-music-elektronische-musik","tag-frank-tischer","tag-fulda","tag-rodgau-hainhausen","tag-thau","tag-the-timekeeper"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p32c1I-7nu","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts\/28364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/comments?post=28364"}],"version-history":[{"count":5,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts\/28364\/revisions"}],"predecessor-version":[{"id":28369,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts\/28364\/revisions\/28369"}],"wp:attachment":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/media?parent=28364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/categories?post=28364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/tags?post=28364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}