{"id":112,"date":"2007-10-08T10:33:14","date_gmt":"2007-10-08T08:33:14","guid":{"rendered":"http:\/\/aliens-project.de\/blog\/?p=112"},"modified":"2010-11-20T16:59:57","modified_gmt":"2010-11-20T15:59:57","slug":"close-up-der-woche-41","status":"publish","type":"post","link":"https:\/\/aliens-project.de\/blog\/2007\/10\/08\/close-up-der-woche-41\/","title":{"rendered":"close up der Woche #41\/07 -Minimoog Voyager"},"content":{"rendered":"<p><a href=\"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2007\/10\/c007-voyager.jpg\"><img decoding=\"async\" src=\"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2007\/10\/c007-voyager.jpg\" alt=\"\" \/><\/a><\/p>\n<p>Der Minimoog Voyager ist,\u00a0seit seinem Erscheinen im Jahr 2002, immer noch\u00a0mein absoluter Lieblings-Synthesizer. Besonders dann, wenn der Sound mal wieder typisch Moog sein soll,\u00a0greife ich meist auf den Voyager\u00a0zur\u00fcck.<\/p>\n<p>Er dient mir, zusammen\u00a0mit dem VX-351 Output-Expander auch als Midi-Interface und Steuerzentrale f\u00fcr den Macbeth M5.<\/p>\n<p>Das ich damals den Mut\u00a0hatte und zu den ersten Vorbestellern geh\u00f6rte,\u00a0noch lange Zeit bevor der\u00a0Name daf\u00fcr\u00a0feststand,\u00a0macht mich\u00a0heute besonders\u00a0happy. So habe ich doch einen der ersten Minimogg Voyager, mit der niedrigen Serial-Number 58 in der limitierten Signature Edition bekommen.<\/p>\n<p>Hier\u00a0findet ihr\u00a0jede Menge <a href=\"http:\/\/www.aliens-project.de\/t_200301_voyager.html\">Samples<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Minimoog Voyager ist,\u00a0seit seinem Erscheinen im Jahr 2002, immer noch\u00a0mein absoluter Lieblings-Synthesizer. Besonders dann, wenn der Sound mal wieder typisch Moog sein soll,\u00a0greife ich meist auf den Voyager\u00a0zur\u00fcck. Er dient mir, zusammen\u00a0mit dem VX-351 Output-Expander auch als Midi-Interface und Steuerzentrale f\u00fcr den Macbeth M5. Das ich damals den Mut\u00a0hatte und zu den ersten Vorbestellern [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,470,4],"tags":[52],"class_list":["post-112","post","type-post","status-publish","format-standard","hentry","category-aliens-project","category-close-up-der-woche","category-synthesizer","tag-synthesizer-minimoog-voyager-signature-edition"],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p32c1I-1O","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/comments?post=112"}],"version-history":[{"count":2,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts\/112\/revisions"}],"predecessor-version":[{"id":11042,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts\/112\/revisions\/11042"}],"wp:attachment":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/media?parent=112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/categories?post=112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/tags?post=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}