{"id":25311,"date":"2014-06-04T08:08:43","date_gmt":"2014-06-04T07:08:43","guid":{"rendered":"http:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07.jpg"},"modified":"2014-06-04T08:08:43","modified_gmt":"2014-06-04T07:08:43","slug":"steinbruch-07","status":"inherit","type":"attachment","link":"https:\/\/aliens-project.de\/blog\/2014\/06\/04\/dietesheimer-steinbrueche\/steinbruch-07\/","title":{"rendered":"Steinbruch-07"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-25311","attachment","type-attachment","status-inherit","hentry"],"smush":"Not processed","jetpack_shortlink":"https:\/\/wp.me\/a32c1I-6Af","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"224\" src=\"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07-300x224.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07-300x224.jpg 300w, https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07-1024x767.jpg 1024w, https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07.jpg 1134w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"25311\" data-permalink=\"https:\/\/aliens-project.de\/blog\/2014\/06\/04\/dietesheimer-steinbrueche\/steinbruch-07\/\" data-orig-file=\"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07.jpg\" data-orig-size=\"1134,850\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;COOLPIX P7800&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1401791788&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;28.4&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Steinbruch-07\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07-1024x767.jpg\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1134,"height":850,"file":"2014\/06\/Steinbruch-07.jpg","sizes":{"thumbnail":{"file":"Steinbruch-07-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07-150x150.jpg"},"medium":{"file":"Steinbruch-07-300x224.jpg","width":300,"height":224,"mime_type":"image\/jpeg","source_url":"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07-300x224.jpg"},"large":{"file":"Steinbruch-07-1024x767.jpg","width":1024,"height":767,"mime_type":"image\/jpeg","source_url":"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07-1024x767.jpg"},"full":{"file":"Steinbruch-07.jpg","width":1134,"height":850,"mime_type":"image\/jpeg","source_url":"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07.jpg"}},"image_meta":{"aperture":3.5,"credit":"","camera":"COOLPIX P7800","caption":"","created_timestamp":1401791788,"copyright":"","focal_length":"28.4","iso":"80","shutter_speed":"0.004","title":""}},"post":25304,"source_url":"https:\/\/aliens-project.de\/blog\/wp-content\/uploads\/2014\/06\/Steinbruch-07.jpg","_links":{"self":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/media\/25311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/comments?post=25311"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":25304,"href":"https:\/\/aliens-project.de\/blog\/wp-json\/wp\/v2\/posts\/25304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}